{"id":2908,"date":"2023-12-14T09:08:50","date_gmt":"2023-12-14T13:08:50","guid":{"rendered":"https:\/\/zenitx.com\/sc\/?post_type=docs&#038;p=2908"},"modified":"2024-01-05T21:35:22","modified_gmt":"2024-01-06T01:35:22","password":"","slug":"ingreso-de-informacion-de-calificaciones-del-sgc","status":"publish","type":"docs","link":"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/","title":{"rendered":"Ingreso de Informaci\u00f3n de Calificaciones del SGC"},"content":{"rendered":"\n<p>Desde cualquier documento (facturas de venta, facturas de compra, ingresos, egresos, reclamos, cotizaciones, oportunidades de mejora, etc.), y desde la tabla de funcionarios, mediante las Herramientas de cada uno, y previo ingreso de la clave VIP del SGC (que permite acceso a generar o modificar la informaci\u00f3n del SGC), tendr\u00e1 acceso a un di\u00e1logo como el siguiente:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"897\" height=\"603\" src=\"https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2023\/12\/image-270.png\" alt=\"\" class=\"wp-image-2910\" style=\"width:583px;height:auto\" srcset=\"https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2023\/12\/image-270.png 897w, https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2023\/12\/image-270-300x202.png 300w, https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2023\/12\/image-270-768x516.png 768w\" sizes=\"(max-width: 897px) 100vw, 897px\" \/><\/figure>\n\n\n\n<p>La calificaci\u00f3n es aplicable al registro actual (sobre el cual se encontraba el cursor cuando accedi\u00f3 a las herramientas desde la tabla o al registro cuando estaba edit\u00e1ndolo). La informaci\u00f3n de tipo y n\u00famero de documento o la identificaci\u00f3n del funcionario, ser\u00e1 mostrada en la cabecera del di\u00e1logo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Clasificaci\u00f3n<\/h2>\n\n\n\n<p>Seg\u00fan se haya definido previamente, de acuerdo al SGC de la empresa, seleccione de la lista disponible en el documento actual, la clasificaci\u00f3n adecuada. Esto es importante, porque, por ejemplo, no es lo mismo una calificaci\u00f3n por encuesta a empresa cliente, que una por observaci\u00f3n interna. Esta clasificaci\u00f3n es usada para las estad\u00edsticas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fecha<\/h2>\n\n\n\n<p>Puede ser igual o superior a la fecha de emisi\u00f3n del documento, e igual o menor a la fecha actual. Se utiliza para decidir si esta calificaci\u00f3n es o no considerada para actualizar la calificaci\u00f3n del cliente (empresa), proveedor o funcionario, dependiendo de la cantidad de calificaciones que por par\u00e1metro se hayan indicado y de las que, por su fecha, sean m\u00e1s recientes a esta.<\/p>\n\n\n\n<p>Puede utilizar la ayuda de calendario disponible.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Calificaci\u00f3n<\/h2>\n\n\n\n<p>Est\u00e1 comprendida entre 1.0 y 7.0, intentando que cada una sea representativa de la observaci\u00f3n. Siempre ofrece la calificaci\u00f3n m\u00e1s alta.<\/p>\n\n\n\n<p>Puede utilizar la ayuda de la calculadora de Sigue\u00ae.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Detalle<\/h2>\n\n\n\n<p>Texto breve, de uso libre, que acompa\u00f1e y describa la calificaci\u00f3n. Es adicional a la clasificaci\u00f3n y es utilizado en los E-mail que puede enviar desde esta tabla.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Informaci\u00f3n<\/h2>\n\n\n\n<p>En realidad, no es parte de los datos que ingresa el usuario y no es modificable (si le hace cambios ser\u00e1n ignorados). Es la informaci\u00f3n que se haya definido para mostrar seg\u00fan la clasificaci\u00f3n elegida, lo que el usuario responsable del SGC habr\u00e1 preparado previamente y podr\u00e1 actualizar cuando requiera.<\/p>\n\n\n\n<p>Su prop\u00f3sito es que, en cada clasificaci\u00f3n, sirva de gu\u00eda para que la calificaci\u00f3n ingresada sea coherente con el SGC y adecuada en su prop\u00f3sito.<\/p>\n\n\n\n<p>El software, adem\u00e1s de la capacidad de adaptarse al modelo de negocios de su empresa, mantiene ciertos est\u00e1ndares:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Rango de notas para calificaci\u00f3n<\/li>\n<\/ul>\n\n\n\n<p>&#8211; Reprobado (Rojo)&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 0.0 a 3.9<\/p>\n\n\n\n<p>&#8211; Debe mejorar (Amarillo) &nbsp;&nbsp;&nbsp;&nbsp; 4.0 a 5.9<\/p>\n\n\n\n<p>&#8211; Cumple requisitos (Verde)&nbsp;&nbsp; 6.0 a 7.0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Idea de las calificaciones<\/li>\n<\/ul>\n\n\n\n<p>1: P\u00e9simo&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 2: Muy Malo&nbsp;&nbsp; 3: Malo<\/p>\n\n\n\n<p>4: Regular&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 5: Bueno<\/p>\n\n\n\n<p>6: Muy Bueno 7: Excelente<\/p>\n\n\n\n<p>En las tablas de Clientes, Proveedores y Funcionarios, al costado izquierdo de cada registro, una columna muestra crayones de 3 colores (precisamente rojo, amarillo y verde), cuando, teniendo la entidad una calificaci\u00f3n promedio registrada, \u00e9sta est\u00e1 comprendida dentro del rango que se grafica con el color correspondiente.<\/p>\n\n\n\n<p>Con un clic sobre la cabecera de dicha columna, se ordenan los registros seg\u00fan su calificaci\u00f3n promedio, primero aquellos que no tienen porque jam\u00e1s se les ha asociado o creado una calificaci\u00f3n, luego los rojos, los amarillos y finalmente los verdes.<\/p>\n\n\n\n<p>De esta forma se puede apreciar y evaluar f\u00e1cilmente la informaci\u00f3n, sin necesidad de recordar n\u00famero o de memorizar escalas.<\/p>\n\n\n\n<p>En el caso de los clientes, es importante, entender que debemos poner \u00e9nfasis en recuperar la imagen que como empresa hemos perdido (rojo), o tenemos en riesgo y debemos mejorar (amarillo), frente a nuestros clientes (las calificaciones a clientes no se refieren, como en los otros casos, a ellos, sino a nosotros frente a ellos).<\/p>\n\n\n\n<p>En caso de los proveedores, aquellos en rojo, dependiendo de la definici\u00f3n de su SGC, quiz\u00e1s deben ser descartados y ya no ser considerados en las cotizaciones o compras, los amarillos deben ser llamados a mejorar su condici\u00f3n.<\/p>\n\n\n\n<p>Trat\u00e1ndose de funcionarios, queda claro que los rojos no podr\u00e1n seguir prestando servicio a la empresa y los amarillos deben ocuparse en mejorar para subir a verde.<\/p>\n\n\n\n<p>La tabla de calificaciones usa esta misma l\u00f3gica para agrupar sus registros, en este caso, adem\u00e1s de poder ordenarlos, cada uno est\u00e1 representado por el color de la calificaci\u00f3n que representa, misma que tambi\u00e9n es mostrada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde cualquier documento (facturas de venta, facturas de compra, ingresos, egresos, reclamos, cotizaciones, oportunidades de mejora, etc.), y desde la tabla de funcionarios, mediante las Herramientas de cada uno, y previo ingreso de la clave VIP del SGC (que permite acceso a generar o modificar la informaci\u00f3n del SGC), tendr\u00e1 acceso a un di\u00e1logo como [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"doc_category":[149],"doc_tag":[],"class_list":["post-2908","docs","type-docs","status-publish","hentry","doc_category-sistema-de-gestion-de-la-calidad"],"year_month":"2026-05","word_count":772,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"Practicante","author_nicename":"practicante","author_url":"https:\/\/zenitx.com\/sc\/author\/practicante\/"},"doc_category_info":[{"term_name":"Sistema de Gesti\u00f3n de la Calidad (SGC)","term_url":"https:\/\/zenitx.com\/sc\/categoria\/sistema-de-gestion-de-la-calidad\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ingreso de Informaci\u00f3n de Calificaciones del SGC - Zenitx Inform\u00e1tica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ingreso de Informaci\u00f3n de Calificaciones del SGC - Zenitx Inform\u00e1tica\" \/>\n<meta property=\"og:description\" content=\"Desde cualquier documento (facturas de venta, facturas de compra, ingresos, egresos, reclamos, cotizaciones, oportunidades de mejora, etc.), y desde la tabla de funcionarios, mediante las Herramientas de cada uno, y previo ingreso de la clave VIP del SGC (que permite acceso a generar o modificar la informaci\u00f3n del SGC), tendr\u00e1 acceso a un di\u00e1logo como [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/\" \/>\n<meta property=\"og:site_name\" content=\"Zenitx Inform\u00e1tica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-06T01:35:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2023\/12\/image-270.png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/\",\"url\":\"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/\",\"name\":\"Ingreso de Informaci\u00f3n de Calificaciones del SGC - Zenitx Inform\u00e1tica\",\"isPartOf\":{\"@id\":\"https:\/\/zenitx.com\/sc\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2023\/12\/image-270.png\",\"datePublished\":\"2023-12-14T13:08:50+00:00\",\"dateModified\":\"2024-01-06T01:35:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/#primaryimage\",\"url\":\"https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2023\/12\/image-270.png\",\"contentUrl\":\"https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2023\/12\/image-270.png\",\"width\":897,\"height\":603},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/zenitx.com\/sc\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manuales\",\"item\":\"https:\/\/zenitx.com\/sc\/know\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ingreso de Informaci\u00f3n de Calificaciones del SGC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/zenitx.com\/sc\/#website\",\"url\":\"https:\/\/zenitx.com\/sc\/\",\"name\":\"Zenitx Inform\u00e1tica\",\"description\":\"Servicio al Cliente\",\"publisher\":{\"@id\":\"https:\/\/zenitx.com\/sc\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/zenitx.com\/sc\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/zenitx.com\/sc\/#organization\",\"name\":\"Zenitx Inform\u00e1tica\",\"url\":\"https:\/\/zenitx.com\/sc\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/zenitx.com\/sc\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2020\/09\/Logo-Zenitx-SC.svg\",\"contentUrl\":\"https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2020\/09\/Logo-Zenitx-SC.svg\",\"width\":330,\"height\":139,\"caption\":\"Zenitx Inform\u00e1tica\"},\"image\":{\"@id\":\"https:\/\/zenitx.com\/sc\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ingreso de Informaci\u00f3n de Calificaciones del SGC - Zenitx Inform\u00e1tica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/","og_locale":"es_ES","og_type":"article","og_title":"Ingreso de Informaci\u00f3n de Calificaciones del SGC - Zenitx Inform\u00e1tica","og_description":"Desde cualquier documento (facturas de venta, facturas de compra, ingresos, egresos, reclamos, cotizaciones, oportunidades de mejora, etc.), y desde la tabla de funcionarios, mediante las Herramientas de cada uno, y previo ingreso de la clave VIP del SGC (que permite acceso a generar o modificar la informaci\u00f3n del SGC), tendr\u00e1 acceso a un di\u00e1logo como [&hellip;]","og_url":"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/","og_site_name":"Zenitx Inform\u00e1tica","article_modified_time":"2024-01-06T01:35:22+00:00","og_image":[{"url":"https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2023\/12\/image-270.png","type":"","width":"","height":""}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/","url":"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/","name":"Ingreso de Informaci\u00f3n de Calificaciones del SGC - Zenitx Inform\u00e1tica","isPartOf":{"@id":"https:\/\/zenitx.com\/sc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/#primaryimage"},"image":{"@id":"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/#primaryimage"},"thumbnailUrl":"https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2023\/12\/image-270.png","datePublished":"2023-12-14T13:08:50+00:00","dateModified":"2024-01-06T01:35:22+00:00","breadcrumb":{"@id":"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/#primaryimage","url":"https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2023\/12\/image-270.png","contentUrl":"https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2023\/12\/image-270.png","width":897,"height":603},{"@type":"BreadcrumbList","@id":"https:\/\/zenitx.com\/sc\/know\/ingreso-de-informacion-de-calificaciones-del-sgc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/zenitx.com\/sc\/"},{"@type":"ListItem","position":2,"name":"Manuales","item":"https:\/\/zenitx.com\/sc\/know\/"},{"@type":"ListItem","position":3,"name":"Ingreso de Informaci\u00f3n de Calificaciones del SGC"}]},{"@type":"WebSite","@id":"https:\/\/zenitx.com\/sc\/#website","url":"https:\/\/zenitx.com\/sc\/","name":"Zenitx Inform\u00e1tica","description":"Servicio al Cliente","publisher":{"@id":"https:\/\/zenitx.com\/sc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zenitx.com\/sc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/zenitx.com\/sc\/#organization","name":"Zenitx Inform\u00e1tica","url":"https:\/\/zenitx.com\/sc\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/zenitx.com\/sc\/#\/schema\/logo\/image\/","url":"https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2020\/09\/Logo-Zenitx-SC.svg","contentUrl":"https:\/\/zenitx.com\/sc\/wp-content\/uploads\/2020\/09\/Logo-Zenitx-SC.svg","width":330,"height":139,"caption":"Zenitx Inform\u00e1tica"},"image":{"@id":"https:\/\/zenitx.com\/sc\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zenitx.com\/sc\/wp-json\/wp\/v2\/docs\/2908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zenitx.com\/sc\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/zenitx.com\/sc\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/zenitx.com\/sc\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/zenitx.com\/sc\/wp-json\/wp\/v2\/comments?post=2908"}],"version-history":[{"count":2,"href":"https:\/\/zenitx.com\/sc\/wp-json\/wp\/v2\/docs\/2908\/revisions"}],"predecessor-version":[{"id":3521,"href":"https:\/\/zenitx.com\/sc\/wp-json\/wp\/v2\/docs\/2908\/revisions\/3521"}],"wp:attachment":[{"href":"https:\/\/zenitx.com\/sc\/wp-json\/wp\/v2\/media?parent=2908"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/zenitx.com\/sc\/wp-json\/wp\/v2\/doc_category?post=2908"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/zenitx.com\/sc\/wp-json\/wp\/v2\/doc_tag?post=2908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}